{"id":40,"date":"2025-07-24T10:30:31","date_gmt":"2025-07-24T10:30:31","guid":{"rendered":"https:\/\/amapbiorillac.com\/?page_id=40"},"modified":"2026-05-05T08:37:39","modified_gmt":"2026-05-05T08:37:39","slug":"producteurs","status":"publish","type":"page","link":"https:\/\/amapbiorillac.com\/index.php\/accueil\/producteurs\/","title":{"rendered":"Producteurs"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"40\" class=\"elementor elementor-40\">\n\t\t\t\t<div class=\"elementor-element elementor-element-05d8b7c e-flex e-con-boxed e-con e-parent\" data-id=\"05d8b7c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0530836 elementor-widget elementor-widget-heading\" data-id=\"0530836\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos producteurs partenaires r\u00e9guliers (pr\u00e9sents toutes les semaines)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca28c29 e-flex e-con-boxed e-con e-parent\" data-id=\"ca28c29\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-49da10e e-con-full e-flex e-con e-child\" data-id=\"49da10e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-76ca35f elementor-widget elementor-widget-image\" data-id=\"76ca35f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/07\/IMG_20250219_100416-01-01-1024x576.jpeg\" class=\"attachment-large size-large wp-image-49\" alt=\"\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/07\/IMG_20250219_100416-01-01-1024x576.jpeg 1024w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/07\/IMG_20250219_100416-01-01-300x169.jpeg 300w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/07\/IMG_20250219_100416-01-01-768x432.jpeg 768w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/07\/IMG_20250219_100416-01-01-1536x864.jpeg 1536w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/07\/IMG_20250219_100416-01-01-2048x1152.jpeg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ed8e94 elementor-widget elementor-widget-heading\" data-id=\"4ed8e94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/amapbiorillac.com\/index.php\/gregory-martin-et-quentin-babia\/\">Le jardin de B\u00e9lestat<br>et<br>EARL du Masgranier<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72c949c elementor-widget elementor-widget-text-editor\" data-id=\"72c949c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Gr\u00e9gory MARTIN<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> et <\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Quentin BABIA<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/span><\/p><p><span style=\"color: #000000;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">L\u00e9gumes de saisons.<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p><p>\u00a0<img decoding=\"async\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/Logo_nature_progres-197x300.gif\" alt=\"\" width=\"34\" height=\"51\" \/><img decoding=\"async\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/07\/download.png\" alt=\"\" width=\"45\" height=\"54\" \/><\/p><p><strong><span style=\"font-size: 14px; font-style: inherit; color: #222222; font-family: Cabin, sans-serif;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-116\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png\" alt=\"\" width=\"41\" height=\"41\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png 178w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240-150x150.png 150w\" sizes=\"(max-width: 41px) 100vw, 41px\" \/>Lacapelle-del-Fraisse et Sansac Veinaz\u00e8s<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p><p><span style=\"color: #000000;\"><strong><span style=\"font-size: 16px; font-style: normal;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Pr\u00e9sent chaque semaine<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3113ab6 e-con-full e-flex e-con e-child\" data-id=\"3113ab6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b40d70f elementor-widget elementor-widget-image\" data-id=\"b40d70f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amapbiorillac.com\/index.php\/anton-zastavnij\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/20251107_161000-225x300.jpg\" class=\"attachment-medium size-medium wp-image-125\" alt=\"\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/20251107_161000-225x300.jpg 225w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/20251107_161000-768x1024.jpg 768w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/20251107_161000-1152x1536.jpg 1152w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/20251107_161000-1536x2048.jpg 1536w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/20251107_161000-scaled.jpg 1920w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6096c3a elementor-widget elementor-widget-heading\" data-id=\"6096c3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bi\u00e8re La chourlie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b676cc7 elementor-widget elementor-widget-text-editor\" data-id=\"b676cc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Anton <\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">ZASTAVNIJ<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/span><\/span><\/p><p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Bi\u00e8re \/ l\u00e9gumes lactoferment\u00e9s\u00a0<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-115 alignnone\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/Logo_nature_progres-197x300.gif\" alt=\"\" width=\"37\" height=\"56\" \/>\u00a0<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-116\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png\" alt=\"\" width=\"44\" height=\"44\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png 178w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240-150x150.png 150w\" sizes=\"(max-width: 44px) 100vw, 44px\" \/><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">S\u00e9nezergues<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p><p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Pr\u00e9sent chaque semaine<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-113052d e-con-full e-flex e-con e-child\" data-id=\"113052d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0533aa4 elementor-widget elementor-widget-image\" data-id=\"0533aa4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amapbiorillac.com\/index.php\/la-ferme-de-bacheluze\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"380\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/481994633_1185844373543556_7029978350440523418_n-1024x608.jpg\" class=\"attachment-large size-large wp-image-130\" alt=\"\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/481994633_1185844373543556_7029978350440523418_n-1024x608.jpg 1024w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/481994633_1185844373543556_7029978350440523418_n-300x178.jpg 300w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/481994633_1185844373543556_7029978350440523418_n-768x456.jpg 768w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/481994633_1185844373543556_7029978350440523418_n-1536x911.jpg 1536w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/481994633_1185844373543556_7029978350440523418_n.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b331bf1 elementor-widget elementor-widget-heading\" data-id=\"b331bf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La ferme de Bacheluze<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66e6421 elementor-widget elementor-widget-text-editor\" data-id=\"66e6421\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">B\u00e9n\u00e9dicte MEURICE<\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p><p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Fromages de ch\u00e8vre<\/span><\/span><\/span><\/span><\/span><\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/07\/download.png\" alt=\"\" width=\"44\" height=\"52\" \/>\u00a0<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-116\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png\" alt=\"\" width=\"44\" height=\"44\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png 178w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240-150x150.png 150w\" sizes=\"(max-width: 44px) 100vw, 44px\" \/><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Moussage<\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p><p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Pr\u00e9sente chaque semaine<\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-488fa6d e-con-full e-flex e-con e-child\" data-id=\"488fa6d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c43a27 elementor-widget elementor-widget-image\" data-id=\"2c43a27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amapbiorillac.com\/index.php\/la-petite-ferme-du-pauzat\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/IMG_9092-225x300.jpg\" class=\"attachment-medium size-medium wp-image-131\" alt=\"\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/IMG_9092-225x300.jpg 225w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/IMG_9092-768x1024.jpg 768w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/IMG_9092-1152x1536.jpg 1152w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/IMG_9092-1536x2048.jpg 1536w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/IMG_9092-scaled.jpg 1920w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6ce400 elementor-widget elementor-widget-heading\" data-id=\"d6ce400\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/amapbiorillac.com\/?page_id=140&#038;preview=true\">La petite ferme de Pauzat<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b96c729 elementor-widget elementor-widget-text-editor\" data-id=\"b96c729\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Sylvie REMY-LENIK<\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p><p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Yaourts, fromages frais et tommes<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/07\/download.png\" alt=\"\" width=\"45\" height=\"54\" \/>\u00a0<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-116\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png\" alt=\"\" width=\"39\" height=\"39\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png 178w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240-150x150.png 150w\" sizes=\"(max-width: 39px) 100vw, 39px\" \/><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Vieillevie<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p><p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Pr\u00e9sent chaque semaine (de janvier \u00e0 ao\u00fbt)<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9d2ec58 e-con-full e-flex e-con e-child\" data-id=\"9d2ec58\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53addc4 elementor-widget elementor-widget-image\" data-id=\"53addc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amapbiorillac.com\/?page_id=196&#038;preview=true\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/131658998_862388611242641_8806753639530603910_n-1024x768.jpg\" class=\"attachment-large size-large wp-image-132\" alt=\"\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/131658998_862388611242641_8806753639530603910_n-1024x768.jpg 1024w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/131658998_862388611242641_8806753639530603910_n-300x225.jpg 300w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/131658998_862388611242641_8806753639530603910_n-768x576.jpg 768w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/131658998_862388611242641_8806753639530603910_n-1536x1152.jpg 1536w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/131658998_862388611242641_8806753639530603910_n.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e68c6d elementor-widget elementor-widget-heading\" data-id=\"1e68c6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Les Br\u00e9mailles de l'Adret<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a3093d elementor-widget elementor-widget-text-editor\" data-id=\"0a3093d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Yohann BIDAULT<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p><p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Boulangerie<\/span><\/span><\/span><\/span><\/span><\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-115\" style=\"font-weight: inherit;\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/Logo_nature_progres-197x300.gif\" alt=\"\" width=\"39\" height=\"59\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/07\/download.png\" alt=\"\" width=\"40\" height=\"48\" \/>\u00a0<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-116\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png\" alt=\"\" width=\"42\" height=\"42\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png 178w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240-150x150.png 150w\" sizes=\"(max-width: 42px) 100vw, 42px\" \/><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Saint Vincent de Salers<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p><p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Pr\u00e9sent chaque semaine<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b61a28c e-con-full e-flex e-con e-child\" data-id=\"b61a28c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0fbc1e6 elementor-widget elementor-widget-image\" data-id=\"0fbc1e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amapbiorillac.com\/index.php\/gaec-de-puy-basset\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/583351962_693111136864054_3339426034476265360_n-1024x576.jpg\" class=\"attachment-large size-large wp-image-133\" alt=\"\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/583351962_693111136864054_3339426034476265360_n-1024x576.jpg 1024w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/583351962_693111136864054_3339426034476265360_n-300x169.jpg 300w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/583351962_693111136864054_3339426034476265360_n-768x432.jpg 768w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/583351962_693111136864054_3339426034476265360_n.jpg 1280w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9cfc9a elementor-widget elementor-widget-heading\" data-id=\"e9cfc9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br><br><br>Gaec De Puy Basset<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bebf772 elementor-widget elementor-widget-text-editor\" data-id=\"bebf772\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Simon et Herv\u00e9 LACALMONIE<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p><p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0152ufs<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/07\/download.png\" alt=\"\" width=\"41\" height=\"49\" \/>\u00a0<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-116\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png\" alt=\"\" width=\"41\" height=\"41\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png 178w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240-150x150.png 150w\" sizes=\"(max-width: 41px) 100vw, 41px\" \/><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Carlat<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p><p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Pr\u00e9sent chaque semaine<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-992668f e-flex e-con-boxed e-con e-parent\" data-id=\"992668f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5885826 elementor-widget elementor-widget-heading\" data-id=\"5885826\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos producteurs partenaires pr\u00e9sents une \u00e0 deux fois par mois<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f562df e-flex e-con-boxed e-con e-parent\" data-id=\"4f562df\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ceceebb e-con-full e-flex e-con e-child\" data-id=\"ceceebb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d44f02d e-con-full e-flex e-con e-child\" data-id=\"d44f02d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc0e151 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"dc0e151\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amapbiorillac.com\/?page_id=201&#038;preview=true\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"635\" height=\"460\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/01\/6834bffd20e60096256616.jpg\" class=\"attachment-large size-large wp-image-213\" alt=\"\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/01\/6834bffd20e60096256616.jpg 635w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/01\/6834bffd20e60096256616-300x217.jpg 300w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1097bcd elementor-widget elementor-widget-heading\" data-id=\"1097bcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La ferme du Bousquin<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a52002 elementor-widget elementor-widget-text-editor\" data-id=\"9a52002\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Jessica MAGNIER<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p><p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Viande de veau, boeuf, plats pr\u00e9par\u00e9s, huile de colza.<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/07\/download.png\" alt=\"\" width=\"53\" height=\"64\" \/><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-116\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png\" alt=\"\" width=\"44\" height=\"44\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png 178w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240-150x150.png 150w\" sizes=\"(max-width: 44px) 100vw, 44px\" \/><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Siran<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p><p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Pr\u00e9sente 2 fois par mois<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-930a502 e-con-full e-flex e-con e-child\" data-id=\"930a502\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-84f09c4 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"84f09c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amapbiorillac.com\/index.php\/les-cueillettes-damelie\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"248\" height=\"300\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/02\/zen-zoom-248x300.jpg\" class=\"attachment-medium size-medium wp-image-224\" alt=\"\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/02\/zen-zoom-248x300.jpg 248w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/02\/zen-zoom.jpg 440w\" sizes=\"(max-width: 248px) 100vw, 248px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efecf49 elementor-widget elementor-widget-heading\" data-id=\"efecf49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les cueillettes d'Am\u00e9lie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bc2e53 elementor-widget elementor-widget-text-editor\" data-id=\"8bc2e53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div><strong>Am\u00e9lie GRANGE<\/strong><\/div><div>\u00a0<\/div><div><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Gemmoth\u00e9rapie, Alcoolature, Hydrolat, Aromates, Infusions.<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/div><div>\u00a0<\/div><div><strong> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/07\/download.png\" alt=\"\" width=\"45\" height=\"54\" \/> <\/strong><\/div><div><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-116\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png\" alt=\"\" width=\"43\" height=\"43\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png 178w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240-150x150.png 150w\" sizes=\"(max-width: 43px) 100vw, 43px\" \/><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Vic-sur-C\u00e8re<\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/div><div>\u00a0<\/div><div><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Pr\u00e9sente 1 fois par mois<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1214253 e-con-full e-flex e-con e-child\" data-id=\"1214253\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f01148 elementor-widget elementor-widget-image\" data-id=\"6f01148\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amapbiorillac.com\/?page_id=202&#038;preview=true\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/02\/IMG_20251105_094734-1024x768.jpg\" class=\"attachment-large size-large wp-image-242\" alt=\"\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/02\/IMG_20251105_094734-1024x768.jpg 1024w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/02\/IMG_20251105_094734-300x225.jpg 300w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/02\/IMG_20251105_094734-768x576.jpg 768w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/02\/IMG_20251105_094734-1536x1152.jpg 1536w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/02\/IMG_20251105_094734-2048x1536.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e83b42 elementor-widget elementor-widget-heading\" data-id=\"9e83b42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La ferme de Martory<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e00496 elementor-widget elementor-widget-text-editor\" data-id=\"2e00496\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Aur\u00e9lie et Sylvain CAUMON<\/strong><\/p><p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Volailles, jus de pommes, cidre, farine, pommes<\/span><\/span><\/span><\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/07\/download.png\" alt=\"\" width=\"47\" height=\"57\" \/><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-116\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png\" alt=\"\" width=\"44\" height=\"44\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png 178w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240-150x150.png 150w\" sizes=\"(max-width: 44px) 100vw, 44px\" \/><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Leynhac<\/span><\/span><\/span><\/span><\/strong><\/p><p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Pr\u00e9sent 1 fois par mois<\/span><\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1cab688 e-con-full e-flex e-con e-child\" data-id=\"1cab688\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95c9a92 elementor-widget elementor-widget-image\" data-id=\"95c9a92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amapbiorillac.com\/?page_id=99&#038;preview=true\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/02\/DSCN7631-768x576-1.jpg\" class=\"attachment-large size-large wp-image-255\" alt=\"\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/02\/DSCN7631-768x576-1.jpg 768w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/02\/DSCN7631-768x576-1-300x225.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-783b4a8 elementor-widget elementor-widget-heading\" data-id=\"783b4a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le d\u00e9lice des petites abeilles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12d88a8 elementor-widget elementor-widget-text-editor\" data-id=\"12d88a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"vw-page-title\"><strong>Isabelle et Sylvain GIACOTTI<\/strong><\/p><p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Apiculture, ch\u00e2taignes, petits fruits et plantes aromatiques<\/span><\/span><\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae0d236 elementor-widget elementor-widget-text-editor\" data-id=\"ae0d236\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/07\/download.png\" alt=\"\" width=\"52\" height=\"62\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-116\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png\" alt=\"\" width=\"39\" height=\"39\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png 178w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240-150x150.png 150w\" sizes=\"(max-width: 39px) 100vw, 39px\" \/><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Leynhac<\/span><\/span><\/strong><\/p><p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Pr\u00e9sent 1x par mois<\/span><\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b311517 e-con-full e-flex e-con e-child\" data-id=\"b311517\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c0a270e elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"c0a270e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amapbiorillac.com\/index.php\/savonnerie-des-adrets\/?preview_id=205&#038;preview_nonce=6e8bed2407&#038;preview=true\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/05\/0254354354.jpg\" class=\"attachment-large size-large wp-image-317\" alt=\"\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/05\/0254354354.jpg 911w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/05\/0254354354-300x300.jpg 300w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/05\/0254354354-150x150.jpg 150w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2026\/05\/0254354354-768x768.jpg 768w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11257cb elementor-widget elementor-widget-heading\" data-id=\"11257cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Savonnerie des Adrets<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4d166c elementor-widget elementor-widget-text-editor\" data-id=\"f4d166c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Soazig PAQUETTE<\/strong><\/p><p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Savons\u00a0<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-115\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/Logo_nature_progres-197x300.gif\" alt=\"\" width=\"43\" height=\"65\" \/><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-116\" src=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png\" alt=\"\" width=\"40\" height=\"40\" srcset=\"https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240.png 178w, https:\/\/amapbiorillac.com\/wp-content\/uploads\/2025\/11\/f47w0-location-icon-png-4240-150x150.png 150w\" sizes=\"(max-width: 40px) 100vw, 40px\" \/><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u00a0 S\u00e9nezergues<\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p><p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Pr\u00e9sente 1 fois par mois<\/span><\/span><\/span><\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e4f2f48 e-con-full e-flex e-con e-child\" data-id=\"e4f2f48\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e314728 e-flex e-con-boxed e-con e-parent\" data-id=\"e314728\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nos producteurs partenaires r\u00e9guliers (pr\u00e9sents toutes les semaines) Le jardin de B\u00e9lestatetEARL du Masgranier Gr\u00e9gory MARTIN et Quentin BABIA L\u00e9gumes de saisons. \u00a0 Lacapelle-del-Fraisse et Sansac Veinaz\u00e8s Pr\u00e9sent chaque semaine Bi\u00e8re La chourlie Anton ZASTAVNIJ Bi\u00e8re \/ l\u00e9gumes lactoferment\u00e9s\u00a0 \u00a0 S\u00e9nezergues Pr\u00e9sent chaque semaine La ferme de Bacheluze B\u00e9n\u00e9dicte MEURICE Fromages de ch\u00e8vre \u00a0 Moussage [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":30,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-40","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/amapbiorillac.com\/index.php\/wp-json\/wp\/v2\/pages\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amapbiorillac.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/amapbiorillac.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/amapbiorillac.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amapbiorillac.com\/index.php\/wp-json\/wp\/v2\/comments?post=40"}],"version-history":[{"count":41,"href":"https:\/\/amapbiorillac.com\/index.php\/wp-json\/wp\/v2\/pages\/40\/revisions"}],"predecessor-version":[{"id":327,"href":"https:\/\/amapbiorillac.com\/index.php\/wp-json\/wp\/v2\/pages\/40\/revisions\/327"}],"up":[{"embeddable":true,"href":"https:\/\/amapbiorillac.com\/index.php\/wp-json\/wp\/v2\/pages\/30"}],"wp:attachment":[{"href":"https:\/\/amapbiorillac.com\/index.php\/wp-json\/wp\/v2\/media?parent=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}